{"id":483,"date":"2016-02-14T16:14:42","date_gmt":"2016-02-14T20:14:42","guid":{"rendered":"http:\/\/www.chaosrequiem.com\/main\/?p=483"},"modified":"2020-10-11T22:44:44","modified_gmt":"2020-10-12T02:44:44","slug":"cancion-de-la-enmienda-los-simpson","status":"publish","type":"post","link":"https:\/\/chaosrequiem.com\/main\/cancion-de-la-enmienda-los-simpson\/","title":{"rendered":"Explicacion de la canci\u00f3n de la enmienda (Los Simpson)"},"content":{"rendered":"<p style=\"text-align: justify;\">Estoy seguro que todos hemos visto alguna vez el cap\u00edtulo de <strong>Los Simpson<\/strong> donde aparece <strong>un ni\u00f1o<\/strong> y una <strong>enmienda constitucional<\/strong> cantando algo que nos parec\u00eda gracioso, aun cuando no entend\u00edamos la canci\u00f3n <strong>por estar en ingl\u00e9s<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-484 size-full\" src=\"http:\/\/www.chaosrequiem.com\/main\/wp-content\/uploads\/2016\/02\/cancion_enmienda.jpg\" alt=\"cancion_enmienda\" width=\"480\" height=\"360\" srcset=\"https:\/\/chaosrequiem.com\/main\/wp-content\/uploads\/2016\/02\/cancion_enmienda.jpg 480w, https:\/\/chaosrequiem.com\/main\/wp-content\/uploads\/2016\/02\/cancion_enmienda-300x225.jpg 300w, https:\/\/chaosrequiem.com\/main\/wp-content\/uploads\/2016\/02\/cancion_enmienda-285x214.jpg 285w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/p>\n<p style=\"text-align: justify;\">Pues bien, esta <strong>&#8220;Canci\u00f3n de la Enmienda&#8221;<\/strong> es en realidad una <strong>parodia<\/strong> de la popular canci\u00f3n llamada <strong>&#8220;I&#8217;m Just a Bill&#8221; (Soy s\u00f3lo un proyecto de ley)\u00a0<\/strong>de &#8220;Schoolhouse Rock!&#8221;, en el cual se explica como una <strong>simple propuesta<\/strong> o enmienda puede pasar a convertirse en una <strong>ley<\/strong> si seguimos al pie de la letra <strong>todo\u00a0el proceso burocr\u00e1tico<\/strong>\u00a0establecido por el gobierno.<\/p>\n<p style=\"text-align: justify;\">Sin dar m\u00e1s vueltas, \u00e9ste es el <strong>video original<\/strong>:<\/p>\n<div class=\"nv-iframe-embed\"><div class=\"lyte-wrapper fourthree\" style=\"width:420px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_pmpamBhEsxc\"><div id=\"lyte_pmpamBhEsxc\" data-src=\"\/\/i.ytimg.com\/vi\/pmpamBhEsxc\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/pmpamBhEsxc\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/pmpamBhEsxc\/0.jpg\" alt=\"YouTube video thumbnail\" width=\"420\" height=\"295\" \/><br \/>Ver este video en YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px auto;\"><\/div><\/div>\n<p style=\"text-align: justify;\">Y \u00e9sta es la <strong>parodia de Los Simpson<\/strong>, la cual ahora llegar\u00e1s a entender gracias a los subt\u00edtulos:<\/p>\n<div class=\"nv-iframe-embed\"><div class=\"lyte-wrapper fourthree\" style=\"width:420px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_G5GC1zUpULE\"><div id=\"lyte_G5GC1zUpULE\" data-src=\"\/\/i.ytimg.com\/vi\/G5GC1zUpULE\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/G5GC1zUpULE\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/G5GC1zUpULE\/0.jpg\" alt=\"YouTube video thumbnail\" width=\"420\" height=\"295\" \/><br \/>Ver este video en YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px auto;\"><\/div><\/div>\n<p style=\"text-align: justify;\">Como habr\u00e1n podido observar, en la parodia hacen una dura <strong>cr\u00edtica al gobierno<\/strong>: <em>la enmienda dice que los ciudadanos tienen &#8220;demasiada libertad&#8221; y que, con tal de aprobar una ley contra la quema de banderas, va a APLASTAR a todo congresista que se le oponga. Al final lo logra: la ratifican y forma parte de la constituci\u00f3n de EEUU. Lo que viene despu\u00e9s es el caos, causado por otras enmiendas, que aparecen a partir de esa &#8220;peque\u00f1a modificaci\u00f3n&#8221; en la constituci\u00f3n<\/em>.<\/p>\n<p style=\"text-align: justify;\">Y\u00a0para rematar el cap\u00edtulo\u00a0cont\u00f3 con la participaci\u00f3n del\u00a0cantante de la canci\u00f3n original:\u00a0<strong>Jack Sheldon.<\/strong><\/p>\n<p style=\"text-align: justify;\">Bueno espero que ahora les haya quedado claro este peque\u00f1o fragmento del episodio de Los Simpson que simplemente les qued\u00f3 genial.<\/p>\n<p style=\"text-align: justify;\">Y para finalizar, dejo un video de mi autor\u00eda que\u00a0hice el d\u00eda de ayer donde cambi\u00e9 la letra de la canci\u00f3n de la enmienda para hacer referencia al <strong>referendum constitucional<\/strong> que tendremos el pr\u00f3ximo domingo 21 de febrero en Bolivia.<\/p>\n<div class=\"nv-iframe-embed\"><div class=\"lyte-wrapper fourthree\" style=\"width:420px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_0kThqhjEMYk\"><div id=\"lyte_0kThqhjEMYk\" data-src=\"\/\/i.ytimg.com\/vi\/0kThqhjEMYk\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/0kThqhjEMYk\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/0kThqhjEMYk\/0.jpg\" alt=\"YouTube video thumbnail\" width=\"420\" height=\"295\" \/><br \/>Ver este video en YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px auto;\"><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Estoy seguro que todos hemos visto alguna vez el cap\u00edtulo de Los Simpson donde aparece un ni\u00f1o y una enmienda constitucional cantando algo que nos parec\u00eda gracioso, aun cuando no entend\u00edamos la canci\u00f3n por estar en ingl\u00e9s. Pues bien, esta &#8220;Canci\u00f3n de la Enmienda&#8221; es en realidad una parodia de la popular canci\u00f3n llamada &#8220;I&#8217;m&hellip;&nbsp;<a href=\"https:\/\/chaosrequiem.com\/main\/cancion-de-la-enmienda-los-simpson\/\" rel=\"bookmark\"><span class=\"screen-reader-text\">Explicacion de la canci\u00f3n de la enmienda (Los Simpson)<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":484,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[12],"tags":[97,94,95,98,93,99,96,100],"class_list":["post-483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notes","tag-bill","tag-cancion","tag-enmienda","tag-jack-sheldon","tag-parodia","tag-referendum","tag-simpson","tag-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Explicacion de la canci\u00f3n de la enmienda - Chaos Requiem<\/title>\n<meta name=\"description\" content=\"Si has visto el cap\u00edtulo de Los Simpson donde aparece un ni\u00f1o y una enmienda constitucional cantando algo en ingl\u00e9s, pues debes saber que es una parodia...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chaosrequiem.com\/main\/cancion-de-la-enmienda-los-simpson\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Explicacion de la canci\u00f3n de la enmienda - Chaos Requiem\" \/>\n<meta property=\"og:description\" content=\"Si has visto el cap\u00edtulo de Los Simpson donde aparece un ni\u00f1o y una enmienda constitucional cantando algo en ingl\u00e9s, pues debes saber que es una parodia...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chaosrequiem.com\/main\/cancion-de-la-enmienda-los-simpson\/\" \/>\n<meta property=\"og:site_name\" content=\"Chaos Requiem\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-14T20:14:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-12T02:44:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chaosrequiem.com\/main\/wp-content\/uploads\/2016\/02\/cancion_enmienda.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lev\u00ed\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lev\u00ed\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/cancion-de-la-enmienda-los-simpson\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/cancion-de-la-enmienda-los-simpson\\\/\"},\"author\":{\"name\":\"Lev\u00ed\",\"@id\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/#\\\/schema\\\/person\\\/4e911944eec9b2e118805c6a3743af83\"},\"headline\":\"Explicacion de la canci\u00f3n de la enmienda (Los Simpson)\",\"datePublished\":\"2016-02-14T20:14:42+00:00\",\"dateModified\":\"2020-10-12T02:44:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/cancion-de-la-enmienda-los-simpson\\\/\"},\"wordCount\":348,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/#\\\/schema\\\/person\\\/4e911944eec9b2e118805c6a3743af83\"},\"image\":{\"@id\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/cancion-de-la-enmienda-los-simpson\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/cancion_enmienda.jpg\",\"keywords\":[\"bill\",\"cancion\",\"enmienda\",\"jack sheldon\",\"parodia\",\"referendum\",\"simpson\",\"video\"],\"articleSection\":[\"Apuntes y Monografias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/cancion-de-la-enmienda-los-simpson\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/cancion-de-la-enmienda-los-simpson\\\/\",\"url\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/cancion-de-la-enmienda-los-simpson\\\/\",\"name\":\"Explicacion de la canci\u00f3n de la enmienda - Chaos Requiem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/cancion-de-la-enmienda-los-simpson\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/cancion-de-la-enmienda-los-simpson\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/cancion_enmienda.jpg\",\"datePublished\":\"2016-02-14T20:14:42+00:00\",\"dateModified\":\"2020-10-12T02:44:44+00:00\",\"description\":\"Si has visto el cap\u00edtulo de Los Simpson donde aparece un ni\u00f1o y una enmienda constitucional cantando algo en ingl\u00e9s, pues debes saber que es una parodia...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/cancion-de-la-enmienda-los-simpson\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/cancion-de-la-enmienda-los-simpson\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/cancion-de-la-enmienda-los-simpson\\\/#primaryimage\",\"url\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/cancion_enmienda.jpg\",\"contentUrl\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/cancion_enmienda.jpg\",\"width\":480,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/cancion-de-la-enmienda-los-simpson\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Explicacion de la canci\u00f3n de la enmienda (Los Simpson)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/#website\",\"url\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/\",\"name\":\"Chaos Requiem\",\"description\":\"Un peque\u00f1o rinc\u00f3n donde pensamientos, ideas y sue\u00f1os muertos cobran vida por un instante.\",\"publisher\":{\"@id\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/#\\\/schema\\\/person\\\/4e911944eec9b2e118805c6a3743af83\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/#\\\/schema\\\/person\\\/4e911944eec9b2e118805c6a3743af83\",\"name\":\"Lev\u00ed\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/cr-logo-2.png\",\"url\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/cr-logo-2.png\",\"contentUrl\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/cr-logo-2.png\",\"width\":109,\"height\":32,\"caption\":\"Lev\u00ed\"},\"logo\":{\"@id\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/cr-logo-2.png\"},\"url\":\"https:\\\/\\\/chaosrequiem.com\\\/main\\\/author\\\/orchestra-conductor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Explicacion de la canci\u00f3n de la enmienda - Chaos Requiem","description":"Si has visto el cap\u00edtulo de Los Simpson donde aparece un ni\u00f1o y una enmienda constitucional cantando algo en ingl\u00e9s, pues debes saber que es una parodia...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chaosrequiem.com\/main\/cancion-de-la-enmienda-los-simpson\/","og_locale":"es_MX","og_type":"article","og_title":"Explicacion de la canci\u00f3n de la enmienda - Chaos Requiem","og_description":"Si has visto el cap\u00edtulo de Los Simpson donde aparece un ni\u00f1o y una enmienda constitucional cantando algo en ingl\u00e9s, pues debes saber que es una parodia...","og_url":"https:\/\/chaosrequiem.com\/main\/cancion-de-la-enmienda-los-simpson\/","og_site_name":"Chaos Requiem","article_published_time":"2016-02-14T20:14:42+00:00","article_modified_time":"2020-10-12T02:44:44+00:00","og_image":[{"width":480,"height":360,"url":"https:\/\/chaosrequiem.com\/main\/wp-content\/uploads\/2016\/02\/cancion_enmienda.jpg","type":"image\/jpeg"}],"author":"Lev\u00ed","twitter_misc":{"Escrito por":"Lev\u00ed","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/chaosrequiem.com\/main\/cancion-de-la-enmienda-los-simpson\/#article","isPartOf":{"@id":"https:\/\/chaosrequiem.com\/main\/cancion-de-la-enmienda-los-simpson\/"},"author":{"name":"Lev\u00ed","@id":"https:\/\/chaosrequiem.com\/main\/#\/schema\/person\/4e911944eec9b2e118805c6a3743af83"},"headline":"Explicacion de la canci\u00f3n de la enmienda (Los Simpson)","datePublished":"2016-02-14T20:14:42+00:00","dateModified":"2020-10-12T02:44:44+00:00","mainEntityOfPage":{"@id":"https:\/\/chaosrequiem.com\/main\/cancion-de-la-enmienda-los-simpson\/"},"wordCount":348,"commentCount":0,"publisher":{"@id":"https:\/\/chaosrequiem.com\/main\/#\/schema\/person\/4e911944eec9b2e118805c6a3743af83"},"image":{"@id":"https:\/\/chaosrequiem.com\/main\/cancion-de-la-enmienda-los-simpson\/#primaryimage"},"thumbnailUrl":"https:\/\/chaosrequiem.com\/main\/wp-content\/uploads\/2016\/02\/cancion_enmienda.jpg","keywords":["bill","cancion","enmienda","jack sheldon","parodia","referendum","simpson","video"],"articleSection":["Apuntes y Monografias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/chaosrequiem.com\/main\/cancion-de-la-enmienda-los-simpson\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/chaosrequiem.com\/main\/cancion-de-la-enmienda-los-simpson\/","url":"https:\/\/chaosrequiem.com\/main\/cancion-de-la-enmienda-los-simpson\/","name":"Explicacion de la canci\u00f3n de la enmienda - Chaos Requiem","isPartOf":{"@id":"https:\/\/chaosrequiem.com\/main\/#website"},"primaryImageOfPage":{"@id":"https:\/\/chaosrequiem.com\/main\/cancion-de-la-enmienda-los-simpson\/#primaryimage"},"image":{"@id":"https:\/\/chaosrequiem.com\/main\/cancion-de-la-enmienda-los-simpson\/#primaryimage"},"thumbnailUrl":"https:\/\/chaosrequiem.com\/main\/wp-content\/uploads\/2016\/02\/cancion_enmienda.jpg","datePublished":"2016-02-14T20:14:42+00:00","dateModified":"2020-10-12T02:44:44+00:00","description":"Si has visto el cap\u00edtulo de Los Simpson donde aparece un ni\u00f1o y una enmienda constitucional cantando algo en ingl\u00e9s, pues debes saber que es una parodia...","breadcrumb":{"@id":"https:\/\/chaosrequiem.com\/main\/cancion-de-la-enmienda-los-simpson\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chaosrequiem.com\/main\/cancion-de-la-enmienda-los-simpson\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/chaosrequiem.com\/main\/cancion-de-la-enmienda-los-simpson\/#primaryimage","url":"https:\/\/chaosrequiem.com\/main\/wp-content\/uploads\/2016\/02\/cancion_enmienda.jpg","contentUrl":"https:\/\/chaosrequiem.com\/main\/wp-content\/uploads\/2016\/02\/cancion_enmienda.jpg","width":480,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/chaosrequiem.com\/main\/cancion-de-la-enmienda-los-simpson\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/chaosrequiem.com\/main\/"},{"@type":"ListItem","position":2,"name":"Explicacion de la canci\u00f3n de la enmienda (Los Simpson)"}]},{"@type":"WebSite","@id":"https:\/\/chaosrequiem.com\/main\/#website","url":"https:\/\/chaosrequiem.com\/main\/","name":"Chaos Requiem","description":"Un peque\u00f1o rinc\u00f3n donde pensamientos, ideas y sue\u00f1os muertos cobran vida por un instante.","publisher":{"@id":"https:\/\/chaosrequiem.com\/main\/#\/schema\/person\/4e911944eec9b2e118805c6a3743af83"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chaosrequiem.com\/main\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/chaosrequiem.com\/main\/#\/schema\/person\/4e911944eec9b2e118805c6a3743af83","name":"Lev\u00ed","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/chaosrequiem.com\/main\/wp-content\/uploads\/2015\/03\/cr-logo-2.png","url":"https:\/\/chaosrequiem.com\/main\/wp-content\/uploads\/2015\/03\/cr-logo-2.png","contentUrl":"https:\/\/chaosrequiem.com\/main\/wp-content\/uploads\/2015\/03\/cr-logo-2.png","width":109,"height":32,"caption":"Lev\u00ed"},"logo":{"@id":"https:\/\/chaosrequiem.com\/main\/wp-content\/uploads\/2015\/03\/cr-logo-2.png"},"url":"https:\/\/chaosrequiem.com\/main\/author\/orchestra-conductor\/"}]}},"_links":{"self":[{"href":"https:\/\/chaosrequiem.com\/main\/wp-json\/wp\/v2\/posts\/483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chaosrequiem.com\/main\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chaosrequiem.com\/main\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chaosrequiem.com\/main\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chaosrequiem.com\/main\/wp-json\/wp\/v2\/comments?post=483"}],"version-history":[{"count":8,"href":"https:\/\/chaosrequiem.com\/main\/wp-json\/wp\/v2\/posts\/483\/revisions"}],"predecessor-version":[{"id":1421,"href":"https:\/\/chaosrequiem.com\/main\/wp-json\/wp\/v2\/posts\/483\/revisions\/1421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chaosrequiem.com\/main\/wp-json\/wp\/v2\/media\/484"}],"wp:attachment":[{"href":"https:\/\/chaosrequiem.com\/main\/wp-json\/wp\/v2\/media?parent=483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chaosrequiem.com\/main\/wp-json\/wp\/v2\/categories?post=483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chaosrequiem.com\/main\/wp-json\/wp\/v2\/tags?post=483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}